{"id":94746,"date":"2025-04-09T15:38:48","date_gmt":"2025-04-09T15:38:48","guid":{"rendered":"https:\/\/wpdepo.com\/urun\/excel-to-learndash-plugin-platinum-edition\/"},"modified":"2025-04-09T15:39:07","modified_gmt":"2025-04-09T15:39:07","slug":"excel-to-learndash-plugin-platinum-edition","status":"publish","type":"product","link":"https:\/\/wpdepo.com\/tr\/urun\/excel-to-learndash-plugin-platinum-edition\/","title":{"rendered":"Excel to LearnDash Plugin &#8211; Platinum Edition"},"content":{"rendered":"<div class=\"row align-center\"  id=\"row-961912653\">\r\n\r\n\n\t<div id=\"col-1647514599\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n<h1 style=\"color: #41476C;\">Excel to LearnDash Plugin - Platinum Edition<\/h1>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1009489795\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(199, 84, 58);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"iso-8859-1\"?>\r\n<!-- Generator: Adobe Illustrator 18.0.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<!DOCTYPE svg PUBLIC \"-\/\/W3C\/\/DTD SVG 1.1\/\/EN\" \"http:\/\/www.w3.org\/Graphics\/SVG\/1.1\/DTD\/svg11.dtd\">\r\n<svg version=\"1.1\" id=\"Capa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 64.167 64.167\" style=\"enable-background:new 0 0 64.167 64.167;\" xml:space=\"preserve\">\r\n<path d=\"M57.506,20.179L40.34,0.346C40.15,0.126,39.874,0,39.583,0H15.417c-4.962,0-9,4.038-9,9v46.167c0,4.962,4.038,9,9,9H48.75\r\n\tc4.962,0,9-4.038,9-9V20.833C57.75,20.593,57.664,20.361,57.506,20.179z M40.583,3.683l13.979,16.15h-6.979c-3.86,0-7-3.14-7-7\r\n\tV3.683z M48.75,62.167H15.417c-3.86,0-7-3.14-7-7V9c0-3.86,3.14-7,7-7h23.167v10.833c0,4.962,4.038,9,9,9h8.167v33.333\r\n\tC55.75,59.027,52.61,62.167,48.75,62.167z M25.791,28.124l-6.529,6.529l6.529,6.529c0.391,0.391,0.391,1.023,0,1.414\r\n\tc-0.195,0.195-0.451,0.293-0.707,0.293s-0.512-0.098-0.707-0.293L17.14,35.36c-0.391-0.391-0.391-1.023,0-1.414l7.236-7.236\r\n\tc0.391-0.391,1.023-0.391,1.414,0S26.181,27.733,25.791,28.124z M47.027,33.946c0.391,0.391,0.391,1.023,0,1.414l-7.236,7.236\r\n\tc-0.195,0.195-0.451,0.293-0.707,0.293s-0.512-0.098-0.707-0.293c-0.391-0.391-0.391-1.023,0-1.414l6.529-6.529l-6.529-6.529\r\n\tc-0.391-0.391-0.391-1.023,0-1.414s1.023-0.391,1.414,0L47.027,33.946z\"\/>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<\/svg>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n\r\n<h4>Versiyon<\/h4>\r\n<p class=\"lead\">4.0\r\n\r\n\t\t<\/div>\n\t<\/div>\n\t\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-975925429\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(199, 84, 58);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"iso-8859-1\"?>\r\n<!-- Generator: Adobe Illustrator 18.0.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<!DOCTYPE svg PUBLIC \"-\/\/W3C\/\/DTD SVG 1.1\/\/EN\" \"http:\/\/www.w3.org\/Graphics\/SVG\/1.1\/DTD\/svg11.dtd\">\r\n<svg version=\"1.1\" id=\"Capa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 57.149 57.149\" style=\"enable-background:new 0 0 57.149 57.149;\" xml:space=\"preserve\">\r\n<path d=\"M57.057,27.474v19.763c0,5.466-4.447,9.913-9.913,9.913H10.005c-5.466,0-9.913-4.447-9.913-9.913V27.474\r\n\tc0-0.552,0.447-1,1-1s1,0.448,1,1v19.763c0,4.363,3.55,7.913,7.913,7.913h37.139c4.363,0,7.913-3.55,7.913-7.913V27.474\r\n\tc0-0.552,0.447-1,1-1S57.057,26.921,57.057,27.474z M10.55,25.724c-0.72-0.719-0.552-1.39-0.446-1.646s0.462-0.849,1.479-0.849h6.5\r\n\tc0.061,0,0.113-0.053,0.113-0.114V2.114C18.197,0.948,19.145,0,20.311,0h16.527c1.166,0,2.114,0.948,2.114,2.114v21.001\r\n\tc0,0.061,0.054,0.114,0.114,0.114h6.499c1.018,0,1.374,0.594,1.479,0.849s0.273,0.927-0.446,1.646L30.07,42.253\r\n\tc-0.398,0.398-0.93,0.618-1.495,0.618s-1.097-0.22-1.495-0.618L10.55,25.724z M12.886,25.229l15.688,15.642\r\n\tc0.022,0,0.055-0.005,0.081-0.032l15.608-15.608l-5.197-0.001c-1.166,0-2.114-0.948-2.114-2.114V2.114\r\n\tc0-0.06-0.055-0.114-0.114-0.114H20.311c-0.06,0-0.114,0.055-0.114,0.114v21.001c0,1.166-0.948,2.114-2.113,2.114H12.886z\"\/>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<\/svg>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n\r\n<h4>Hemen \u0130ndir<\/h4>\r\n<p class=\"lead\"><a class=\"download-link\" title=\"\u0130ndir &ldquo;Excel to LearnDash Plugin - Platinum Edition&rdquo;&nbsp;Versiyon 4.0\" href=\"https:\/\/wpdepo.com\/tr\/\/download\/12589\/\" rel=\"nofollow\">\n\t\u0130ndir<\/a>\r\n\r\n\t\t<\/div>\n\t<\/div>\n\t\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-381709752\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(199, 84, 58);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"iso-8859-1\"?>\r\n<!-- Generator: Adobe Illustrator 18.0.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<!DOCTYPE svg PUBLIC \"-\/\/W3C\/\/DTD SVG 1.1\/\/EN\" \"http:\/\/www.w3.org\/Graphics\/SVG\/1.1\/DTD\/svg11.dtd\">\r\n<svg version=\"1.1\" id=\"Capa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 58.5 58.5\" style=\"enable-background:new 0 0 58.5 58.5;\" xml:space=\"preserve\">\r\n<path d=\"M29.25,0C13.121,0,0,13.122,0,29.25S13.121,58.5,29.25,58.5S58.5,45.378,58.5,29.25S45.379,0,29.25,0z M29.25,56.5\r\n\tC14.225,56.5,2,44.276,2,29.25S14.225,2,29.25,2S56.5,14.224,56.5,29.25S44.275,56.5,29.25,56.5z M45.5,30.417c0,0.552-0.447,1-1,1\r\n\tH29.25c-0.347,0-0.669-0.18-0.851-0.475l-9.54-15.46c-0.29-0.47-0.145-1.086,0.325-1.376c0.472-0.291,1.087-0.145,1.376,0.326\r\n\tl9.247,14.985H44.5C45.053,29.417,45.5,29.864,45.5,30.417z\"\/>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<\/svg>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n\r\n<h4>G\u00fcncelleme<\/h4>\r\n<p class=\"lead\">15 \u015eubat 2018\r\n\r\n\t\t<\/div>\n\t<\/div>\n\t\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1952922386\" class=\"col medium-3 small-6 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"color:rgb(199, 84, 58);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"iso-8859-1\"?>\r\n<!-- Generator: Adobe Illustrator 18.0.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\r\n<!DOCTYPE svg PUBLIC \"-\/\/W3C\/\/DTD SVG 1.1\/\/EN\" \"http:\/\/www.w3.org\/Graphics\/SVG\/1.1\/DTD\/svg11.dtd\">\r\n<svg version=\"1.1\" id=\"Capa_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 62.634 62.634\" style=\"enable-background:new 0 0 62.634 62.634;\" xml:space=\"preserve\">\r\n<path d=\"M55.228,13.102H31.625l-1.998-5.47c-1.575-4.26-5.76-4.26-7.771-4.26H4.606C2.066,3.372,0,5.439,0,7.979v43.877\r\n\tc0,4.084,3.323,7.406,7.407,7.406h47.821c4.084,0,7.407-3.322,7.407-7.406V20.509C62.634,16.425,59.312,13.102,55.228,13.102z\r\n\t M60.634,51.856c0,2.981-2.425,5.406-5.407,5.406H7.407C4.425,57.262,2,54.837,2,51.856V7.979c0-1.437,1.169-2.606,2.606-2.606\r\n\th17.249c2.431,0,4.888,0.228,5.894,2.95l2.237,6.123c0.144,0.395,0.52,0.657,0.939,0.657h24.302c2.981,0,5.407,2.425,5.407,5.407\r\n\tV51.856z M54.567,25.871c0,0.552-0.448,1-1,1h-44.5c-0.552,0-1-0.448-1-1s0.448-1,1-1h44.5\r\n\tC54.12,24.871,54.567,25.319,54.567,25.871z\"\/>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<g>\r\n<\/g>\r\n<\/svg>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\r\n\r\n<h4>Kategori<\/h4>\r\n<p class=\"lead\">LearnDash LMS\r\n\r\n\t\t<\/div>\n\t<\/div>\n\t\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[578],"product_tag":[],"class_list":{"0":"post-94746","1":"product","2":"type-product","3":"status-publish","5":"product_cat-learndash-eklentileri","7":"first","8":"instock","9":"virtual","10":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/product\/94746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/media?parent=94746"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/product_brand?post=94746"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/product_cat?post=94746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wpdepo.com\/tr\/wp-json\/wp\/v2\/product_tag?post=94746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}